{"id":27,"date":"2021-07-15T14:24:54","date_gmt":"2021-07-15T14:24:54","guid":{"rendered":"http:\/\/aziendaagricolamammarella.com\/?page_id=27"},"modified":"2024-12-04T11:09:05","modified_gmt":"2024-12-04T11:09:05","slug":"shop","status":"publish","type":"page","link":"https:\/\/aziendaagricolamammarella.com\/en\/shop\/","title":{"rendered":"Shop"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27\" class=\"elementor elementor-27\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad3f1dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad3f1dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db209a2\" data-id=\"db209a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4228a66 elementor-widget elementor-widget-spacer\" data-id=\"4228a66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a234b1 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5a234b1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9caaa69\" data-id=\"9caaa69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdd0f51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdd0f51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acfc6c6\" data-id=\"acfc6c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd932b3 elementor-widget elementor-widget-spacer\" data-id=\"fd932b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49e8894 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49e8894\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbb9dd2\" data-id=\"fbb9dd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a2c786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a2c786\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-470fc99\" data-id=\"470fc99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7206661 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"7206661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/passata-e-pelati\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Passata e pelati<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1c9293f\" data-id=\"1c9293f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-906e744 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"906e744\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/sughi-pronti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sughi pronti<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-31759a8\" data-id=\"31759a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c7d37 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"29c7d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/olio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Olio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d327206\" data-id=\"d327206\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25c9f42 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"25c9f42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/legumi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Legumi<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f96ca1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f96ca1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6eb9af2\" data-id=\"6eb9af2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4e04cd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e4e04cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/sottolio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sott'olio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4a9a3bb\" data-id=\"4a9a3bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0abf13 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c0abf13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/miele-e-composte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Miele e composte<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-52ad14e\" data-id=\"52ad14e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac85bc elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5ac85bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/speciale\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Speciale<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0eaff9c\" data-id=\"0eaff9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3b801b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"d3b801b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aziendaagricolamammarella.com\/en\/shop\/agrodolce\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Confetture<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa3b12 eael-product-grid-column-tablet-2 eael-product-grid-column-4 elementor-widget elementor-widget-eicon-woocommerce\" data-id=\"0aa3b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid eael-product-simple grid\" id=\"eael-product-grid\" data-widget-id=\"0aa3b12\" data-page-id=\"27\" data-nonce=\"974ca3b222\" >\n            <div class=\"woocommerce\">\n                <ul class=\"products eael-post-appender eael-post-appender-0aa3b12\" data-ssi-desktop=\"no\" data-ssi-tablet=\"no\" data-ssi-mobile=\"no\" data-layout-mode=\"grid\"> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/box-regalo-degustazione-natale-2025\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Box Regalo Degustazione Natale 2025\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/box-regalo-degustazione-natale-2025\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Box Regalo Degustazione Natale 2025<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>49.99<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=2528\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2528\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"2528\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Box Regalo Degustazione Natale 2025&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Box Regalo Degustazione Natale 2025&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2528\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/le-sfoglie-di-pomodoro-pelato-senza-semi-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-768x768.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Le Sfoglie di pomodoro pelato senza semi - 500g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-768x768.jpeg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-300x300.jpeg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-1024x1024.jpeg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-150x150.jpeg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-1536x1536.jpeg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-12x12.jpeg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-500x500.jpeg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-100x100.jpeg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/le-sfoglie-di-pomodoro-pelato-senza-semi-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Le Sfoglie di pomodoro pelato senza semi - 500g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.70<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>54.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.70 through &euro;54.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/le-sfoglie-di-pomodoro-pelato-senza-semi-500g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2445\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"2445\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Le Sfoglie di pomodoro pelato senza semi - 500g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2445\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pomodori Pelati in barattolo grande - 540 g.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pomodori Pelati in barattolo grande - 540 g.<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.50<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>39.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;3.50 through &euro;39.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_620\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"620\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodori Pelati in barattolo grande - 540 g.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_620\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Passata di pomodoro in bottiglia - 720 ml.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Passata di pomodoro in bottiglia - 720 ml.<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.80<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>30.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;2.80 through &euro;30.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_618\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"618\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Passata di pomodoro in bottiglia - 720 ml.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_618\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo-500-g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pomodorino Salsato in barattolo \u2013 500 g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo-500-g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pomodorino Salsato in barattolo \u2013 500 g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.50<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>40.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;3.50 through &euro;40.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo-500-g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2506\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2506\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodorino Salsato in barattolo \u2013 500 g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2506\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pomodorino Salsato in barattolo - 280 g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pomodorino Salsato in barattolo - 280 g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.40<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>67.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;2.40 through &euro;67.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2498\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2498\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodorino Salsato in barattolo - 280 g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2498\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Olio EVO \u201cGentile di Larino\u201d DOP\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Olio EVO \u201cGentile di Larino\u201d DOP<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>11.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.00 through &euro;11.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_624\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"624\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Olio EVO \u201cGentile di Larino\u201d DOP&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_624\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino-in-latta\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Olio EVO \u201cGentile di Larino\u201d in Latta DOP\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino-in-latta\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Olio EVO \u201cGentile di Larino\u201d in Latta DOP<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>15.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>70.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;15.00 through &euro;70.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino-in-latta\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1990\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1990\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Olio EVO \u201cGentile di Larino\u201d in Latta DOP&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1990\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/carciofini-in-olio-extravergine-gentile-di-larino-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/carciofini-in-olio-extravergine-gentile-di-larino-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1974\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1974\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1974\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1974\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/zucchine-secche-in-olio-extravergine-gentile-di-larino-212g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/zucchine-secche-in-olio-extravergine-gentile-di-larino-212g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.00<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1960\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1960\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1960\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1960\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/fafucce\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/fafucce\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/fafucce\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1948\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1948\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1948\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-secchi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-secchi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1946\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1946\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1946\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1946\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olive\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olive\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>7.50<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olive\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_623\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"623\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_623\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/melanzane-in-olio\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/melanzane-in-olio\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.00<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=621\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_621\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"621\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_621\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pallotte-cacio-e-ova-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pallotte cacio e ova - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pallotte-cacio-e-ova-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pallotte cacio e ova - 314g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>6.00<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pallotte-cacio-e-ova-314g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1983\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1983\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Pallotte cacio e ova - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1983\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/sugo-alle-olive-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Rag\u00f9 Vegetale - 260g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/sugo-alle-olive-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Rag\u00f9 Vegetale - 260g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1980\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1980\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1980\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Rag\u00f9 Vegetale - 260g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Rag\u00f9 Vegetale - 260g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1980\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/miele-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Miele di coriandolo\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/miele-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Miele di coriandolo<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>14.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.00 through &euro;14.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/miele-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1947\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1947\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Miele di coriandolo&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1947\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/composta-di-mele-e-cannella-110g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Composta di mele e cannella - 95g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/composta-di-mele-e-cannella-110g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Composta di mele e cannella - 95g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.80<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/composta-di-mele-e-cannella-110g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1985\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1985\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Composta di mele e cannella - 95g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1985\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/gelatina-di-tintilia-90g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-768x768.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Gelatina di Tintilia - 90g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-768x768.jpeg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-300x300.jpeg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-1024x1024.jpeg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-150x150.jpeg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-1536x1536.jpeg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-12x12.jpeg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-500x500.jpeg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-100x100.jpeg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/gelatina-di-tintilia-90g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Gelatina di Tintilia - 90g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/gelatina-di-tintilia-90g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1984\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1984\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Gelatina di Tintilia - 90g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1984\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati-in-barattolo-piccolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Pomodori Pelati in barattolo piccolo - 290 g.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati-in-barattolo-piccolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pomodori Pelati in barattolo piccolo - 290 g.<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1.90<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>55.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;1.90 through &euro;55.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati-in-barattolo-piccolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2003\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2003\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodori Pelati in barattolo piccolo - 290 g.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2003\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Ceci cotti al naturale - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Ceci cotti al naturale - 314g<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.80<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_622\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"622\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Ceci cotti al naturale - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_622\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata-di-pomodoro-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Passata di pomodoro in barattolo - 290 ml.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata-di-pomodoro-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Passata di pomodoro in barattolo - 290 ml.<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1.80<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>49.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;1.80 through &euro;49.00<\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata-di-pomodoro-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2000\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2000\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Passata di pomodoro in barattolo - 290 ml.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2000\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci-secchi-300-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-768x768.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Ceci secchi - 500g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-768x768.png 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-300x300.png 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-1024x1024.png 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-150x150.png 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-1536x1536.png 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-2048x2048.png 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-500x500.png 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-100x100.png 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci-secchi-300-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Ceci secchi - 500g<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div>    <a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1957\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1957\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1957\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Ceci secchi - 500g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ceci secchi - 500g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1957\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/confezione-collector-etition\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-768x768.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Confezione Collector Edition\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/confezione-collector-etition\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Confezione Collector Edition<\/h2><\/a>\n    <\/div><span class=\"outofstock-badge sale-preset-1 \">Out of stock<\/span><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>55.00<\/bdi><\/span><\/div>    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/confezione-collector-etition\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1986\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1986\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Confezione Collector Edition&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1986\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li><\/ul>            <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-0aa3b12\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1169dab elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1169dab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c627534\" data-id=\"c627534\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b897a8d eael-product-gallery-column-4 elementor-widget elementor-widget-eael-woo-product-gallery\" data-id=\"b897a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_product_gallery_column&quot;:&quot;4&quot;}\" data-widget_type=\"eael-woo-product-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-gallery eael-product-preset-4 masonry eael-terms-layout-horizontal\" id=\"eael-product-gallery\" data-widget-id=\"b897a8d\" data-page-id=\"27\" data-nonce=\"8985d72c19\" >\n\t\t\t<ul class=\"eael-cat-tab\" data-layout=\"masonry\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;preset-4.php&quot;,&quot;name&quot;:&quot;Woo-Product-Gallery&quot;}\" data-nonce=\"8985d72c19\" data-page-id=\"27\" data-widget-id=\"b897a8d\" data-widget=\"b897a8d\" data-class=\"Essential_Addons_Elementor\\Elements\\Woo_Product_Gallery\" data-args=\"post_type=product&amp;post_status=publish&amp;posts_per_page=24&amp;order=desc&amp;offset=0&amp;tax_query%5Brelation%5D=AND&amp;tax_query%5B0%5D%5Btaxonomy%5D=product_visibility&amp;tax_query%5B0%5D%5Bfield%5D=name&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=exclude-from-search&amp;tax_query%5B0%5D%5Bterms%5D%5B1%5D=exclude-from-catalog&amp;tax_query%5B0%5D%5Boperator%5D=NOT+IN&amp;tax_query%5B1%5D%5Brelation%5D=OR&amp;tax_query%5B1%5D%5B0%5D%5Btaxonomy%5D=product_cat&amp;tax_query%5B1%5D%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B0%5D=22&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B1%5D=34&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B2%5D=24&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B3%5D=36&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B4%5D=35&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B5%5D=33&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B6%5D=29&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B7%5D=38&amp;tax_query%5B1%5D%5B0%5D%5Boperator%5D=IN&amp;orderby=date&amp;meta_query%5Brelation%5D=AND\" data-page=\"1\"><li><a href=\"javascript:;\" data-taxonomy=\"product_cat\" data-page=\"1\" data-tagid=\"\" data-id=\"[&quot;22&quot;,&quot;34&quot;,&quot;24&quot;,&quot;36&quot;,&quot;35&quot;,&quot;33&quot;,&quot;29&quot;,&quot;38&quot;]\" class=\"active post-list-filter-item post-list-cat-b897a8d\">Tutti<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"pomodori\"]' data-id=\"22\" class=\"post-list-filter-item \">Passata e pelati<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"sughi-pronti\"]' data-id=\"34\" class=\"post-list-filter-item \">Sughi pronti<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"olio\"]' data-id=\"24\" class=\"post-list-filter-item \">Olio<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"legumi\"]' data-id=\"36\" class=\"post-list-filter-item \">Legumi<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"confetture\"]' data-id=\"35\" class=\"post-list-filter-item \">Confetture<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"sottolio\"]' data-id=\"33\" class=\"post-list-filter-item \">Sott&#039;olio<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"miele\"]' data-id=\"29\" class=\"post-list-filter-item \">Miele e composte<\/a><\/li><li><a href=\"javascript:;\" data-page=\"1\" data-taxonomy=\"product_cat\" data-terms='[\"speciale\"]' data-id=\"38\" class=\"post-list-filter-item \">Speciale<\/a><\/li><\/ul>\n            <div class=\"woocommerce\">\n\t\t\t\t<ul class=\"products eael-post-appender eael-post-appender-b897a8d\" data-layout-mode=\"masonry\" data-ssi-desktop=\"no\" ><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/box-regalo-degustazione-natale-2025\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Box Regalo Degustazione Natale 2025\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/12\/CHRI.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Box Regalo Degustazione Natale 2025<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>49.99<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=2528\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2528\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"2528\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Box Regalo Degustazione Natale 2025&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Box Regalo Degustazione Natale 2025&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2528\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/le-sfoglie-di-pomodoro-pelato-senza-semi-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"Le Sfoglie di pomodoro pelato senza semi - 500g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-768x768.jpeg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-300x300.jpeg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-1024x1024.jpeg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-150x150.jpeg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-1536x1536.jpeg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-12x12.jpeg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-500x500.jpeg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001-100x100.jpeg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e001.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Le Sfoglie di pomodoro pelato senza semi - 500g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.70<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>54.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.70 through &euro;54.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/le-sfoglie-di-pomodoro-pelato-senza-semi-500g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2445\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"2445\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Le Sfoglie di pomodoro pelato senza semi - 500g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2445\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pomodori Pelati in barattolo grande - 540 g.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/pelati-1.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pomodori Pelati in barattolo grande - 540 g.<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.50<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>39.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;3.50 through &euro;39.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_620\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"620\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodori Pelati in barattolo grande - 540 g.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_620\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Passata di pomodoro in bottiglia - 720 ml.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/passata-1.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Passata di pomodoro in bottiglia - 720 ml.<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.80<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>30.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;2.80 through &euro;30.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_618\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"618\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Passata di pomodoro in bottiglia - 720 ml.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_618\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo-500-g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pomodorino Salsato in barattolo \u2013 500 g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/pomodorini-salsati.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pomodorino Salsato in barattolo \u2013 500 g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.50<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>40.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;3.50 through &euro;40.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo-500-g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2506\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2506\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodorino Salsato in barattolo \u2013 500 g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2506\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pomodorino Salsato in barattolo - 280 g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2025\/04\/POMODIRINI-SALSATI-2.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pomodorino Salsato in barattolo - 280 g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.40<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>67.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;2.40 through &euro;67.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodorino-salsato-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2498\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2498\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodorino Salsato in barattolo - 280 g&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2498\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Olio EVO \u201cGentile di Larino\u201d DOP\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/bottiglia-olio.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Olio EVO \u201cGentile di Larino\u201d DOP<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>11.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.00 through &euro;11.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_624\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"624\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Olio EVO \u201cGentile di Larino\u201d DOP&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_624\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino-in-latta\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Olio EVO \u201cGentile di Larino\u201d in Latta DOP\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olio-evo-latta.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Olio EVO \u201cGentile di Larino\u201d in Latta DOP<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>15.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>70.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;15.00 through &euro;70.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olio-evo-gentile-di-larino-in-latta\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1990\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1990\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Olio EVO \u201cGentile di Larino\u201d in Latta DOP&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1990\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/carciofini-in-olio-extravergine-gentile-di-larino-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-25-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1974\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1974\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1974\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carciofini in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1974\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/zucchine-secche-in-olio-extravergine-gentile-di-larino-212g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/zucchine.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.00<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1960\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1960\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1960\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Zucchine secche in olio Extravergine \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1960\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/fafucce\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/fafucce.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/fafucce\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1948\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1948\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;\u201cFafucce\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1948\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-secchi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pomodori-secchi.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.50<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1946\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1946\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1946\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pomodori secchi in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1946\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olive\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/olive.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>7.50<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/olive\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_623\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"623\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Olive \u201cCapate\u201d in olio Extravergine di oliva \u201cGentile di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_623\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/melanzane-in-olio\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/melanzane.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>8.00<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=621\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_621\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"621\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Melanzane in olio Extravergine Di Oliva \u201cGentile Di Larino\u201d DOP - 314g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_621\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pallotte-cacio-e-ova-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pallotte cacio e ova - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-24-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pallotte cacio e ova - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>6.00<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pallotte-cacio-e-ova-314g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1983\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1983\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Pallotte cacio e ova - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1983\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/sugo-alle-olive-314g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Rag\u00f9 Vegetale - 260g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-12x12.jpg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/RAGU-VEGETALE.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Rag\u00f9 Vegetale - 260g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1980\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1980\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1980\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Rag\u00f9 Vegetale - 260g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Rag\u00f9 Vegetale - 260g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1980\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/miele-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Miele di coriandolo\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-22-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Miele di coriandolo<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>14.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;4.00 through &euro;14.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/miele-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1947\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1947\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Miele di coriandolo&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1947\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/composta-di-mele-e-cannella-110g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Composta di mele e cannella - 95g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-27-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Composta di mele e cannella - 95g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3.80<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/composta-di-mele-e-cannella-110g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1985\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1985\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Composta di mele e cannella - 95g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1985\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/gelatina-di-tintilia-90g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-768x768.jpeg\" class=\"attachment-medium_large size-medium_large\" alt=\"Gelatina di Tintilia - 90g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-768x768.jpeg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-300x300.jpeg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-1024x1024.jpeg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-150x150.jpeg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-1536x1536.jpeg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-12x12.jpeg 12w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-500x500.jpeg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002-100x100.jpeg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/\u200emammarella.\u200e002.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Gelatina di Tintilia - 90g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/gelatina-di-tintilia-90g\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1984\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1984\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Gelatina di Tintilia - 90g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1984\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati-in-barattolo-piccolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Pomodori Pelati in barattolo piccolo - 290 g.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/pelati.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Pomodori Pelati in barattolo piccolo - 290 g.<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1.90<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>55.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;1.90 through &euro;55.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/pomodori-pelati-in-barattolo-piccolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2003\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2003\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Pomodori Pelati in barattolo piccolo - 290 g.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2003\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Ceci cotti al naturale - 314g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/07\/ceci.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Ceci cotti al naturale - 314g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2.80<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_622\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"622\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Ceci cotti al naturale - 314g&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_622\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata-di-pomodoro-in-barattolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Passata di pomodoro in barattolo - 290 ml.\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata-100x100.jpg 100w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/passata.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Passata di pomodoro in barattolo - 290 ml.<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1.80<\/bdi><\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>49.00<\/bdi><\/span><span class=\"screen-reader-text\">Price range: &euro;1.80 through &euro;49.00<\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/passata-di-pomodoro-in-barattolo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2000\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"2000\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Passata di pomodoro in barattolo - 290 ml.&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2000\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/ceci-secchi-300-500g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-768x768.png\" class=\"attachment-medium_large size-medium_large\" alt=\"Ceci secchi - 500g\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-768x768.png 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-300x300.png 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-1024x1024.png 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-150x150.png 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-1536x1536.png 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-2048x2048.png 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-500x500.png 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/ceci-secchi-busta_Tavola-disegno-1-copia-21-100x100.png 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Ceci secchi - 500g<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>4.00<\/bdi><\/span><\/div><a href=\"\/en\/wp-json\/wp\/v2\/pages\/27?add-to-cart=1957\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1957\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1957\" data-product_sku=\"\" aria-label=\"Add to basket: &ldquo;Ceci secchi - 500g&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ceci secchi - 500g&rdquo; has been added to your basket\" role=\"button\">Add to basket<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1957\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><li class=\"product \">\n        <div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\" >\n    <span class=\"eael-onsale outofstock sale-preset-1 \">Prodotto esaurito<\/span><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/confezione-collector-etition\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-768x768.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Confezione Collector Edition\" loading=\"eager\" srcset=\"https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-768x768.jpg 768w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-300x300.jpg 300w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-1024x1024.jpg 1024w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-150x150.jpg 150w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-1536x1536.jpg 1536w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-2048x2048.jpg 2048w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-500x500.jpg 500w, https:\/\/aziendaagricolamammarella.com\/wp-content\/uploads\/2021\/11\/Senza-titolo-1_Tavola-disegno-1-copia-23-1-100x100.jpg 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><h2 class=\"woocommerce-loop-product__title\">Confezione Collector Edition<\/h2><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>55.00<\/bdi><\/span><\/div><a href=\"https:\/\/aziendaagricolamammarella.com\/en\/product\/confezione-collector-etition\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1986\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1986\" data-product_sku=\"\" aria-label=\"Read more about &ldquo;Confezione Collector Edition&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1986\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    <\/div>\n<\/li><\/ul>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"hide-load-more eael-load-more-button\" id=\"eael-load-more-btn-b897a8d\" data-widget-id=\"b897a8d\" data-widget=\"b897a8d\" data-page-id=\"27\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;preset-4.php&quot;,&quot;name&quot;:&quot;Woo-Product-Gallery&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Woo_Product_Gallery\" data-layout=\"masonry\" data-page=\"1\" data-args=\"post_type=product&amp;post_status=publish&amp;posts_per_page=24&amp;order=desc&amp;offset=0&amp;tax_query%5Brelation%5D=AND&amp;tax_query%5B0%5D%5Btaxonomy%5D=product_visibility&amp;tax_query%5B0%5D%5Bfield%5D=name&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=exclude-from-search&amp;tax_query%5B0%5D%5Bterms%5D%5B1%5D=exclude-from-catalog&amp;tax_query%5B0%5D%5Boperator%5D=NOT+IN&amp;tax_query%5B1%5D%5Brelation%5D=OR&amp;tax_query%5B1%5D%5B0%5D%5Btaxonomy%5D=product_cat&amp;tax_query%5B1%5D%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B0%5D=22&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B1%5D=34&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B2%5D=24&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B3%5D=36&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B4%5D=35&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B5%5D=33&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B6%5D=29&amp;tax_query%5B1%5D%5B0%5D%5Bterms%5D%5B7%5D=38&amp;tax_query%5B1%5D%5B0%5D%5Boperator%5D=IN&amp;orderby=date&amp;meta_query%5Brelation%5D=AND\" data-max-page=\"1\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Carica altro<\/span>\n                <\/button>\n            <\/div>\n                        <\/div>\n        <\/div>\n        <script type=\"text\/javascript\">\n\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\tvar $scope = jQuery(\".elementor-element-b897a8d\");\n\t\t\t\tvar $products = $('.products', $scope);\n\t\t\t\tvar $layout_mode = $products.data('layout-mode');\n\n\t\t\t\tif ($layout_mode === 'masonry') {\n\t\t\t\t\t\/\/ init isotope\n\t\t\t\t\tvar $isotope_products = $products.isotope({ itemSelector: \"li.product\", layoutMode: $layout_mode, percentPosition: true });\n\t\t\t\t\t$isotope_products.imagesLoaded().progress(function () {\n\t\t\t\t\t\t$isotope_products.isotope('layout');\n\t\t\t\t\t})\n\n\t\t\t\t\t$(window).on('resize', function () {\n\t\t\t\t\t\t$isotope_products.isotope('layout');\n\t\t\t\t\t});\n\t\t\t\t}\n\t\t\t});\n        <\/script>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Passata e pelati Sughi pronti Olio Legumi Sott&#8217;olio Miele e composte Speciale Confetture Le Sfoglie di pomodoro pelato senza semi &#8211; 500g &euro;4.70 &ndash; &euro;54.00 Scegli Questo prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto Box Degustazione Pasqua &euro;50.00 Select options Pomodori Pelati in barattolo piccolo &#8211; 290 g. &euro;1.90 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":187,"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":2496,"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/pages\/27\/revisions\/2496"}],"wp:attachment":[{"href":"https:\/\/aziendaagricolamammarella.com\/en\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}